{"id":100,"date":"2025-03-10T10:42:07","date_gmt":"2025-03-10T10:42:07","guid":{"rendered":"https:\/\/www.clinicairibarren.es\/?page_id=100"},"modified":"2025-04-01T19:30:29","modified_gmt":"2025-04-01T19:30:29","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de Privacidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"100\" class=\"elementor elementor-100\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8f2101 e-flex e-con-boxed e-con e-parent\" data-id=\"d8f2101\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-695ef372 elementor-widget elementor-widget-text-editor\" data-id=\"695ef372\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"p1\">AVISO LEGAL<\/h1>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><!-- \/wp:paragraph --><!-- wp:heading --><\/p>\n<p class=\"p1\">Gracias por visitar este sitio web.<\/p>\n<p class=\"p1\">Lee detenidamente los T\u00e9rminos y Condiciones que constan en este documento, ya que el uso de este sitio web implica la expresa y plena aceptaci\u00f3n de los mismos, en la versi\u00f3n publicada en el momento en que accedes al mismo. Le recomendamos que lea atentamente este documento cada vez que acceda al sitio web para comprobar si ha habido cambios en las condiciones de uso y lo abandone si no est\u00e1 de acuerdo con dichos cambios. Si creemos que ciertas modificaciones son importantes, actualizaremos la fecha de \u00ab\u00daltima modificaci\u00f3n\u00bb en la parte superior de esta p\u00e1gina. Usted ser\u00e1 el responsable de revisar y familiarizarse con cualquier modificaci\u00f3n realizada.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading --><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p class=\"p1\"><b>LEYES QUE INCORPORA ESTA POL\u00cdTICA DE PRIVACIDAD<\/b><strong class=\"privacy-policy-tutorial\">:<\/strong><\/p>\n<p class=\"p1\">Esta pol\u00edtica est\u00e1 adaptada a las siguientes normas, que se encuentran actualmente en vigor, tanto en Espa\u00f1a como en Europa:<\/p>\n<p class=\"p1\">El Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD).<\/p>\n<p class=\"p1\">La Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales (LOPD-GDD).<\/p>\n<p class=\"p1\">La Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE).<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading --><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p><strong class=\"privacy-policy-tutorial\">IDENTIFICACI\u00d3N:<\/strong><\/p>\n<p class=\"p1\">En cumplimiento con el deber de informaci\u00f3n recogido en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico con la legislaci\u00f3n vigente en materia de protecci\u00f3n de datos, en concreto, la Ley org\u00e1nica 3\/2018, de 5 de diciembre, de protecci\u00f3n de datos personales y garant\u00eda de los derechos digitales (LOPDDGG) que hace plenamente efectiva la aplicaci\u00f3n del Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo de 27 de abril de 2016 relativo a la protecci\u00f3n de las personas f\u00edsicas en el que respeta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD).<\/p>\n<p class=\"p1\"><b>Responsable del Tratamiento: <\/b>Luc\u00eda Iribarren Mac\u00edas (en adelante <b>LA EMPRESA<\/b>)<\/p>\n<p class=\"p1\"><b>Nombre Comercial: <\/b>CL\u00cdNICA IRIBARREN<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading --><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p><strong class=\"privacy-policy-tutorial\">COMUNICACI\u00d3N: <\/strong><\/p>\n<p class=\"p1\">Para contactar con nosotros para cualquier cuesti\u00f3n que haga referencia al tratamiento de datos<span class=\"Apple-converted-space\">\u00a0 <\/span>personales, ponemos a su disposici\u00f3n diferentes medios de contacto que detallamos a continuaci\u00f3n:<\/p>\n<p class=\"p1\"><b>Tel\u00e9fono:<\/b> +34 981 29 88 97<\/p>\n<p class=\"p2\"><b>Correo electr\u00f3nico: <\/b>luciribarren@gmail.com<\/p>\n<p class=\"p2\"><b>Domicilio Social: <\/b>C\/ Alcalde Marchesi, 10\/12 \u2013 2\u00ba Izq. 15006 A Coru\u00f1a<\/p>\n<p class=\"p3\"><span class=\"s2\"><b>P\u00e1gina Web: <\/b>www.clinicairibarren.es<\/span><\/p>\n<p class=\"p2\">Todas las notificaciones y comunicaciones facilitadas en este apartado se considerar\u00e1n eficaces, a todos los efectos, cuando se realicen a trav\u00e9s de cualquier medio de los detallados anteriormente.\u00a0<\/p>\n<p class=\"p2\">Nosotros entendemos que la privacidad y la seguridad de su informaci\u00f3n personal son extremadamente importantes. Por eso, esta pol\u00edtica establece lo que hacemos con su informaci\u00f3n y lo que hacemos para mantenerla segura.\u00a0 Tambi\u00e9n explica d\u00f3nde y c\u00f3mo recopilamos su informaci\u00f3n personal, as\u00ed como sus derechos sobre cualquier informaci\u00f3n personal que tengamos sobre usted<span class=\"s3\">.<\/span><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading --><\/p>\n<p class=\"p1\"><b>Principios aplicables al tratamiento de los datos personales<\/b><\/p>\n<p class=\"p1\">El tratamiento de los datos personales del Usuario se someter\u00e1 a los siguientes principios recogidos en el art\u00edculo 5 del RGPD y en el art\u00edculo 4 y siguientes de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales:<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">Principio de licitud, lealtad y transparencia: se requerir\u00e1 en todo momento el consentimiento del Usuario previa informaci\u00f3n completamente transparente de los fines para los cuales se recogen los datos personales.<\/li>\n<li class=\"li1\">Principio de limitaci\u00f3n de la finalidad: los datos personales ser\u00e1n recogidos con fines determinados, expl\u00edcitos y leg\u00edtimos.<\/li>\n<li class=\"li1\">Principio de minimizaci\u00f3n de datos: los datos personales recogidos ser\u00e1n \u00fanicamente los estrictamente necesarios en relaci\u00f3n con los fines para los que son tratados.<\/li>\n<li class=\"li1\">Principio de exactitud: los datos personales deben ser exactos y estar siempre actualizados.<\/li>\n<li class=\"li1\">Principio de limitaci\u00f3n del plazo de conservaci\u00f3n: los datos personales solo ser\u00e1n mantenidos de forma que se permita la identificaci\u00f3n del Usuario durante el tiempo necesario para los fines de su tratamiento.<\/li>\n<li class=\"li1\">Principio de integridad y confidencialidad: los datos personales ser\u00e1n tratados de manera que se garantice su seguridad y confidencialidad.<\/li>\n<li class=\"li1\">Principio de responsabilidad proactiva: el Responsable del tratamiento ser\u00e1 responsable de asegurar que los principios anteriores se cumplen.<\/li>\n<\/ul>\n<p><!-- \/wp:paragraph --><!-- wp:heading --><\/p>\n<p class=\"p1\"><b>\u00bfQu\u00e9 medidas hemos tomado para asegurar la confidencialidad, integridad y seguridad de sus datos?<\/b><\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">Solo pedimos la cantidad m\u00ednima de informaci\u00f3n necesaria, recopilando solo lo que creemos que es esencial para hacer negocios o para la transacci\u00f3n espec\u00edfica que corresponda;<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\">Hemos establecido una serie de acuerdos de confidencialidad con todos nuestros proveedores, personal y colaboradores;<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\">Contamos con una asesor\u00eda especializada que no solo nos asistir\u00e1 de forma permanente en esta materia sino que adem\u00e1s realizar\u00e1 controles peri\u00f3dicos para asegurar el correcto cumplimiento de esta normativa;<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\">Hemos establecido una serie de medidas de seguridad inform\u00e1tica que nos proteger\u00e1 de posibles ataques externos;<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\">Hemos revisado toda nuestra documentaci\u00f3n de modo que sea la adecuada seg\u00fan lo establecido en el nuevo reglamento;<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\">Hemos evaluado el impacto que pueden causar nuestros procedimientos sobre la protecci\u00f3n de sus datos personales;<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\">Hemos formado nuestro personal para que todos podamos actuar de forma diligente y \u00e9tica, cumpliendo con todas las exigencias previstas en el nuevo reglamento.<\/li>\n<\/ul>\n<p><b>Principios que aplicaremos a tu informaci\u00f3n personal<\/b><\/p>\n<p class=\"p3\">En el tratamiento de tus datos personales, aplicaremos los siguientes principios que se ajustan a las exigencias del nuevo reglamento europeo de protecci\u00f3n de datos:<\/p>\n<ul class=\"ul1\">\n<li class=\"li4\"><b>Principio de licitud, lealtad y transparencia:<\/b>\u00a0Siempre vamos a requerir tu consentimiento para el tratamiento de tus datos personales para uno o varios fines espec\u00edficos que te informaremos previamente con absoluta transparencia.<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li4\"><b>Principio de minimizaci\u00f3n de datos:<\/b>\u00a0Solo vamos a solicitar datos estrictamente necesarios en relaci\u00f3n con los fines para los que los requerimos. Los m\u00ednimos posibles.<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li4\"><b>Principio de limitaci\u00f3n del plazo de conservaci\u00f3n:<\/b>\u00a0los datos ser\u00e1n mantenidos durante no m\u00e1s tiempo del necesario para los fines del tratamiento, en funci\u00f3n a la finalidad, te informaremos del plazo de conservaci\u00f3n correspondiente, en el caso de suscripciones, peri\u00f3dicamente revisaremos nuestras listas y eliminaremos aquellos registros inactivos durante un tiempo considerable.<\/li>\n<li class=\"li4\"><b>Principio de integridad y confidencialidad:<\/b>\u00a0Tus datos ser\u00e1n tratados de tal manera que se garantice una seguridad adecuada de los datos personales y se garantice confidencialidad. Debes saber que tomamos todas las precauciones necesarias para evitar el acceso no autorizado o uso indebido de los datos de nuestros usuarios por parte de terceros.<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\u00a0<\/li>\n<\/ul>\n<p><!-- \/wp:paragraph --><\/p>\n<p class=\"p1\"><b>BASES JURIDICAS PARA LA RECOPILACI\u00d3N Y USO DE LA INFORMACION <\/b><\/p>\n<p class=\"p1\">Si usted es un individuo en el Espacio Econ\u00f3mico Europeo (EEE), nuestra base jur\u00eddica para la recolecci\u00f3n y el uso de informaci\u00f3n depende de la informaci\u00f3n personal en cuesti\u00f3n y del contexto en el que la recopilamos. La mayor\u00eda de nuestras actividades de recopilaci\u00f3n y procesamiento de informaci\u00f3n generalmente se basan en:<\/p>\n<p class=\"p1\">1) una necesidad contractual;<\/p>\n<p class=\"p1\">2) uno o varios intereses leg\u00edtimos de <em>LA EMPRESA<\/em> o un tercero que no se anulen por sus intereses de protecci\u00f3n de datos o<\/p>\n<p class=\"p1\">3) su consentimiento. A veces, tendremos la obligaci\u00f3n legal de recopilar su informaci\u00f3n o necesitaremos su informaci\u00f3n personal para proteger sus intereses vitales o los de otra persona.<\/p>\n<p class=\"p1\"><b>TRATAMIENTOS<\/b><\/p>\n<p class=\"p1\">Le explicaremos, a continuaci\u00f3n, c\u00f3mo recogemos, utilizamos, divulgamos, transferimos y almacenamos su informaci\u00f3n. La presente Pol\u00edtica de privacidad es aplicable a la informaci\u00f3n de car\u00e1cter personal recogida a trav\u00e9s de nuestro sitio web. Es importante que consulte con frecuencia la Pol\u00edtica de privacidad por si se ha actualizado.<\/p>\n<p class=\"p1\">Todos los usuarios que acceden a nuestra p\u00e1gina web podr\u00e1n conocer todo su contenido sin la necesidad de facilitar ninguna informaci\u00f3n de car\u00e1cter personal. \u00a0Sus datos personales solo ser\u00e1n recabados cuando usted cumplimente voluntariamente nuestro(s) formulario(s). En este caso, el usuario garantiza la autenticidad, exactitud y veracidad de la informaci\u00f3n facilitada, comprometi\u00e9ndose a mantener actualizados los datos de car\u00e1cter personal de forma que los mismos respondan, en todo momento, a su situaci\u00f3n real. El usuario ser\u00e1 el \u00fanico responsable de las manifestaciones falsas o inexactas y de los perjuicios que las mismas pudieran causar. Mediante esta v\u00eda de comunicaci\u00f3n usted acepta de forma expresa recibir comunicaciones peri\u00f3dicas \u00fanicamente de la entidad, que guardar\u00e1 los datos personales que reciba de los usuarios a trav\u00e9s de la p\u00e1gina web en total secreto, garantizando su confidencialidad, y adoptar\u00e1 las medidas t\u00e9cnicas necesarias para evitar cualquier alteraci\u00f3n, p\u00e9rdida, mal uso, o acceso no autorizado a estos datos.<\/p>\n<p class=\"p1\">Asimismo, le comunicamos que todos los datos facilitados a trav\u00e9s de formularios electr\u00f3nicos y\/o mediante correo electr\u00f3nico son los estrictamente necesarios para la correcta identificaci\u00f3n del remitente. Esta informaci\u00f3n ser\u00e1 tratada con estricta confidencialidad y con la \u00fanica finalidad de realizar la gesti\u00f3n de solicitudes de informaci\u00f3n, contrataci\u00f3n de nuestros servicios y productos y otras finalidades que est\u00e1n especificadas a continuaci\u00f3n. Usted queda informado y presta su pleno consentimiento expreso para utilizar sus datos para las actividades relacionadas al objeto social de la entidad.<\/p>\n<p class=\"p3\">El consentimiento prestado, tanto para el tratamiento como para la cesi\u00f3n de los datos de los interesados, es revocable en cualquier momento comunic\u00e1ndolo a la direcci\u00f3n de correo electr\u00f3nico luciairibarren@gmail.com\u00a0en los t\u00e9rminos establecidos en esta Pol\u00edtica para el ejercicio de los derechos. Esta revocaci\u00f3n en ning\u00fan caso tendr\u00e1 car\u00e1cter retroactivo.<\/p>\n<p class=\"p1\"><b>C\u00f3mo utilizamos sus datos<\/b><\/p>\n<p class=\"p1\">Podemos utilizar sus datos personales de la siguiente manera:\u00a0la informaci\u00f3n que usted nos proporciones nos podr\u00e1 ayudar en la toma de decisiones, a responder solicitudes, mejorar los servicios, detectar nuevas necesidades, generar promociones, entender sus expectativas y proporcionarle un mejor servicio. Tambi\u00e9n podremos utilizar sus datos para las siguientes gestiones.<\/p>\n<p class=\"p1\"><b>Procesar su pedido y proporcionarle sus productos y servicios\u00a0<\/b><\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">Procesar el pedido de los productos y servicios que nos ha comprado y mantenerle informado de su progreso;<\/li>\n<li class=\"li1\">Proporcionarle el producto o servicio correspondiente.<\/li>\n<\/ul>\n<p class=\"p1\"><b>Facturaci\u00f3n y Atenci\u00f3n al Cliente<\/b>\u00a0<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">Para facturarle o cobrarle por el uso de nuestros productos y servicios;<\/li>\n<li class=\"li1\">Contactarle si la informaci\u00f3n de facturaci\u00f3n que nos proporcionaste no est\u00e1 actualizada, va a caducar o no podemos aceptar el pago;\u00a0<\/li>\n<li class=\"li1\">Responder a cualquier pregunta o inquietud que pueda tener sobre nuestros, productos o servicios<\/li>\n<\/ul>\n<p class=\"p1\"><b>Mensajes de informaci\u00f3n de servicio<\/b>\u00a0<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">Nos pondremos en contacto usted para mantenerle actualizado con informaci\u00f3n sobre los productos y servicios que tiene con nosotros.<\/li>\n<\/ul>\n<p class=\"p1\"><b>Otras gestiones: <\/b><\/p>\n<p class=\"p1\"><b>Raz\u00f3n espec\u00edfica.<\/b><\/p>\n<p class=\"p1\">Si proporciona sus datos personales para un fin en concreto, los utilizaremos para lo relacionado con el fin para el cual se proporcionaron. Por ejemplo, si usted se pone en contacto con nosotros por correo electr\u00f3nico, utilizaremos los datos personales que nos facilite para responder a su pregunta o solucionar el problema, y responderemos a la direcci\u00f3n de correo electr\u00f3nico desde la que se envi\u00f3 el mensaje.\u00a0<\/p>\n<p class=\"p1\"><b>Fines internos.<\/b>\u00a0<\/p>\n<p class=\"p1\">Podemos usar sus datos personales para fines internos como, por ejemplo, para basarnos en ellos con el fin de mejorar el contenido y la funcionalidad de los servicios, comprender mejor la necesidad de nuestros clientes, mejorar los servicios, proteger, identificar o abordar actividades fraudulentas, reforzar nuestros t\u00e9rminos de servicio, gestionar su cuenta y proporcionarle servicio de atenci\u00f3n al cliente y, de manera general, gestionar los servicios y nuestra actividad comercial, entre otros.\u00a0<\/p>\n<p class=\"p1\"><b>Comunicaciones comerciales. <\/b><\/p>\n<p class=\"p1\">Siempre que contemos con su consentimiento expreso (que se obtendr\u00e1 mediante una casilla exclusiva presente en nuestros formularios), podremos usar sus datos personales para ponernos en contacto con usted en el futuro para la realizaci\u00f3n de acciones comerciales que puedan ser de su inter\u00e9s, siempre relacionadas con los productos y\/o servicios que ofrece la empresa. En cualquier caso, usted siempre tendr\u00e1 disponible la opci\u00f3n \u00abdejar de recibir\u00bb estos mensajes electr\u00f3nicos en la parte inferior de dichos mensajes o notificarlo a nosotros enviando un correo electr\u00f3nico a la siguiente direcci\u00f3n: luciairibarren@gmail.com. Sin embargo, usted podr\u00e1 seguir recibiendo avisos y correos electr\u00f3nicos siempre que sean necesarios y esenciales para el mantenimiento de nuestras transacciones contractuales. De acuerdo con la Ley 34\/2002, de 11 de julio, de servicios de la sociedad de la informaci\u00f3n y de comercio electr\u00f3nico. (LSSICE) <em>LA EMPRESA<\/em> no realiza pr\u00e1cticas de SPAM y se compromete a no enviar comunicaciones de car\u00e1cter comercial sin identificarlas debidamente.<\/p>\n<p class=\"p1\">Le rogamos tenga en cuenta que aunque decida no suscribirse o se d\u00e9 de baja de las comunicaciones electr\u00f3nicas promocionales o comerciales puede que <em>LA EMPRESA<\/em> siga necesitando contactar con usted como Usuario con informaci\u00f3n importante sobre transacciones relativas a su cuenta y a sus compras de productos, reserva de actividades o contrataci\u00f3n de otros servicios.<\/p>\n<p class=\"p1\">A continuaci\u00f3n, explicamos de forma m\u00e1s detallada qu\u00e9 tipos de datos se recogen y se tratan y cu\u00e1les son sus finalidades:<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-512\" src=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18-1024x425.png\" alt=\"\" width=\"700\" height=\"290\" srcset=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18-1024x425.png 1024w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18-300x124.png 300w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18-768x319.png 768w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18.png 1094w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p class=\"p1\">Las bases legales se enlazan con las finalidades del punto anterior<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-514\" src=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.09-1024x477.png\" alt=\"\" width=\"700\" height=\"326\" srcset=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.09-1024x477.png 1024w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.09-300x140.png 300w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.09-768x358.png 768w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.09.png 1090w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p class=\"p1\">Datos facilitados voluntariamente por el interesado<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-513 size-large\" src=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.20.08-683x1024.png\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.20.08-683x1024.png 683w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.20.08-200x300.png 200w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.20.08-768x1152.png 768w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.20.08-1024x1536.png 1024w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.20.08.png 1104w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-517\" src=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.24.34-300x105.png\" alt=\"\" width=\"700\" height=\"244\" srcset=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.24.34-300x105.png 300w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.24.34-1024x358.png 1024w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.24.34-768x268.png 768w, https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.24.34.png 1094w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p class=\"p1\"><b>OTROS ASPECTOS RELACIONADOS CON LA CESI\u00d3N DE DATOS<\/b><\/p>\n<p class=\"p1\">Por regla general, los datos que usted nos facilita no son revelados a terceros sin su consentimiento, salvo obligaci\u00f3n legal, por ejemplo: en caso de una citaci\u00f3n judicial o una solicitud de un organismo gubernamental, o si creemos de buena fe que dicha acci\u00f3n es necesaria para a) para cumplir con una obligaci\u00f3n jur\u00eddica; b) para proteger o defender nuestros derechos, intereses o propiedades, o los de un tercero; c) para prevenir o investigar il\u00edcitos potenciales en relaci\u00f3n con los Servicios; d) para actuar en circunstancias de urgencia para proteger su seguridad personal; o e) para resguardar contra responsabilidades jur\u00eddicas.\u00a0<\/p>\n<p class=\"p1\"><b>ALMACENAMIENTO<\/b><\/p>\n<p class=\"p1\">Podemos almacenar sus datos o transferirlos a un tercero que los almacenar\u00e1 de conformidad con esta Pol\u00edtica de privacidad. Adoptamos las medidas que consideramos razonables para proteger los datos personales contra p\u00e9rdida, mal uso, uso no autorizado, acceso no autorizado, divulgaci\u00f3n involuntaria, modificaci\u00f3n y destrucci\u00f3n. Sin embargo, no existen redes, servidores, bases de datos ni transmisiones por Internet o correo electr\u00f3nico completamente seguras o exentas de errores. En el caso de que se produzca una violaci\u00f3n de la seguridad de los datos que se encuentran bajo nuestra custodia, tomaremos todas las medidas<span class=\"Apple-converted-space\">\u00a0 <\/span>necesarias para mitigar sus consecuencias y notificaremos este hecho a la Autoridad de Control, juntamente con toda la informaci\u00f3n relevante para la documentaci\u00f3n y comunicaci\u00f3n de la incidencia.<\/p>\n<p class=\"p1\"><b>CONSENTIMIENTOS<\/b><\/p>\n<p class=\"p1\">El consentimiento del interesado, atendiendo a lo que enuncia la normativa de protecci\u00f3n de datos, se trata de una comunicaci\u00f3n libre por parte del interesado por la cual acepta que se traten sus datos, para una finalidad concreta, bajo unas determinadas condiciones, de las cuales tiene que estar previamente informado.<\/p>\n<p class=\"p1\"><b>\u00bfPuede modificar o retirar sus consentimientos cuando quiera?<\/b><\/p>\n<p class=\"p1\">Por supuesto que s\u00ed. La informaci\u00f3n de los tratamientos que ha consentido estar\u00e1 siempre accesible. Podr\u00e1 modificarla o retirarla siempre que quiera a trav\u00e9s de nuestro correo electr\u00f3nico.<br \/>As\u00ed mismo, puede darse de baja de nuestra BBDD en el momento que lo desee, envi\u00e1ndonos un mail a: luciairibarren@gmail.com.<\/p>\n<p class=\"p1\"><b>DECISIONES AUTOMATIZADAS <\/b><\/p>\n<p class=\"p1\"><b>LA EMPRESA<\/b> no adopta decisi\u00f3n alguna basada \u00fanicamente en el tratamiento automatizado de sus datos.<\/p>\n<p class=\"p1\"><b>ESTUDIOS ESTATISTICOS<\/b><\/p>\n<p class=\"p1\"><b>LA EMPRESA<\/b> no realiza estudios con fines cient\u00edficos, hist\u00f3ricos y estad\u00edsticos en cuyo caso se procurar\u00e1 la disociaci\u00f3n del dato al objeto del estudio para preservar su confidencialidad.<\/p>\n<p class=\"p1\"><b>AVISO DE VIOLACI\u00d3N DE DATOS PERSONALES O BRECHAS DE SEGURIDAD.<\/b><\/p>\n<p class=\"p1\">La violaci\u00f3n de datos personales supone una brecha de la seguridad de los sistemas de informaci\u00f3n de <em>LA EMPRESA<\/em> que provoca o puede provocar la destrucci\u00f3n, alteraci\u00f3n, p\u00e9rdida, divulgaci\u00f3n no autorizada o acceso, accidental o no, a los datos personales transmitidos, almacenados o procesados relacionados con la prestaci\u00f3n de nuestros servicios. Para el caso de que los datos personales que almacenamos y\/o tratamos en <em>LA EMPRESA<\/em> se vean comprometidos de alguna forma, procederemos a notificar oportunamente a los afectados, y conforme a lo dispuesto en el art\u00edculo 33 del RGPD<\/p>\n<p class=\"p1\"><b>DERECHOS DE PROTECCI\u00d3N DE DATOS <\/b><\/p>\n<p class=\"p1\">Los usuarios podr\u00e1n dirigir una comunicaci\u00f3n por escrito al domicilio social de <em>LA EMPRESA<\/em> o a la direcci\u00f3n de correo electr\u00f3nico indicada en el encabezamiento de este Aviso Legal para solicitar el ejercicio de los derechos siguientes:<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\"><b>Derecho de rectificaci\u00f3n de datos personales<\/b>. Usted tiene derecho a rectificar informaci\u00f3n guardada sobre usted si \u00e9sta no es precisa. Si la informaci\u00f3n que almacenamos necesita actualizarse, o uste cree que puede ser err\u00f3nea, puede actualizarla cuando juzgue necesario.<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\"><b>Derecho de acceso a datos personales<\/b>. Usted tiene derecho a solicitar una copia de los datos personales que guardamos de usted.<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\"><b>Derecho a la portabilidad de los datos.<\/b><span class=\"Apple-converted-space\">\u00a0 <\/span>Usted tienes derecho a transportar los datos que nos ha proporcionado en ciertas circunstancias.<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\"><b>Derecho de oposici\u00f3n al uso de datos personales<\/b>. Usted tienes el derecho a oponerse al procesamiento de tu informaci\u00f3n personal<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\"><b>Derecho de cancelaci\u00f3n<\/b>. Nosotros nos esforzamos en procesar y retener sus datos solo el tiempo que necesitemos. Asimismo, usted tiene el derecho a solicitar la cancelaci\u00f3n de sus datos personales que tenemos guardados. Estos datos se conservar\u00e1n bloqueados y accesibles \u00fanicamente por determinadas personas para el caso de que los necesitemos para atender alguna reclamaci\u00f3n o responder de nuestras obligaciones.<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\"><b>Derecho de limitaci\u00f3n. <\/b>Usted tiene el derecho a solicitar la limitaci\u00f3n del tratamiento de tus datos de manera que nosotros podamos almacenar tus datos, pero no usarlos.<\/li>\n<\/ul>\n<p class=\"p1\">Adem\u00e1s de los medios espec\u00edficos establecidos para cada derecho, podr\u00e1s ejercitar tus derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n, oposici\u00f3n, limitaci\u00f3n y portabilidad, as\u00ed como revocar los consentimientos dados, dirigi\u00e9ndose por escrito con la referencia \u201cProtecci\u00f3n de Datos\u201d, a la direcci\u00f3n postal o electr\u00f3nica informada en el encabezado de esta Pol\u00edtica.<\/p>\n<p class=\"p1\">Estos derechos son personal\u00edsimos y ser\u00e1n ejercidos por el interesado, sin otras limitaciones que las que prevea la legislaci\u00f3n aplicable. Podr\u00e1, no obstante, actuar el representante legal del usuario interesado cuando \u00e9ste se encuentre en situaci\u00f3n de incapacidad o minor\u00eda de edad que le imposibilite el ejercicio personal de los mismos. El ejercicio de sus derechos se har\u00e1 efectivo por el Responsable del Tratamiento dentro de treinta d\u00edas siguientes al de la recepci\u00f3n de la solicitud. En el supuesto de que el Responsable del Tratamiento considere que no procede acceder a lo solicitado, se lo comunicar\u00e1 motivadamente y dentro del plazo se\u00f1alado en este apartado. En los casos en que, siendo procedente la cancelaci\u00f3n de los datos, no sea posible su extinci\u00f3n f\u00edsica, tanto por razones t\u00e9cnicas como por causa del soporte inform\u00e1tico utilizado, nosotros procederemos el bloqueo de los mismos con el fin de impedir su utilizaci\u00f3n, hasta que su completa eliminaci\u00f3n de los sistemas de informaci\u00f3n.<\/p>\n<p class=\"p1\"><b>RECOGIDA DE DATOS DE MENORES<\/b><\/p>\n<p class=\"p1\">Nuestra p\u00e1gina web no est\u00e1 destinada a menores de 16 a\u00f1os. No recopilamos informaci\u00f3n de forma intencionada (incluidos Datos personales) sobre ni\u00f1os ni otras personas que legalmente no pueden utilizar nuestros servicios. Si tenemos conocimiento de haber recopilado datos personales de un ni\u00f1o menor de 16 a\u00f1os, procederemos a su eliminaci\u00f3n a la mayor brevedad, a menos que estemos legalmente obligados a conservar dichos datos.\u00a0<\/p>\n<p class=\"p1\"><b>P\u00f3ngase en contacto con nosotros<\/b> si cree que hemos recopilado informaci\u00f3n de un menor de 16 a\u00f1os por error o de forma no intencionada envi\u00e1ndonos un e-mail a la direcci\u00f3n de correo electr\u00f3nico: luciribarren@gmail.com.<\/p>\n<p class=\"p1\"><b>TRATAMIENTOS DE CATEGORIAS ESPECIALES DE DATOS PERSONALES Y DATOS PERSONALES RELATIVOS A CONDENAS E INFRACCIONES PENALES<\/b><b><\/b><\/p>\n<p class=\"p1\">En la formalizaci\u00f3n de los campos de texto libre no se permite la introducci\u00f3n de informaci\u00f3n personal relativa a datos personales que revelen el origen \u00e9tnico o racial, las opiniones pol\u00edticas, las convicciones religiosas o filos\u00f3ficas, o la afiliaci\u00f3n sindical, y el tratamiento de datos gen\u00e9ticos, datos biom\u00e9tricos dirigidos a identificar de manera un\u00edvoca a una persona f\u00edsica, datos relativos a la salud o datos relativos a la vida sexual o las orientaciones sexuales de una persona f\u00edsica, as\u00ed como datos personales relativos a condenas e infracciones penales. En caso de introducir alguna informaci\u00f3n relativa a los aspectos mencionados en cualquiera de nuestros formularios o a trav\u00e9s del correo electr\u00f3nico ser\u00e1n inmediatamente borrados de nuestros sistemas de informaci\u00f3n sin poder atender la consulta realizada, ya que tales datos no son necesarios ni pertinentes para las finalidades determinadas en los tratamientos de esta Web.<\/p>\n<p class=\"p1\"><b>RECLAMACI\u00d3N ANTE LA AUTORIDAD DE CONTROL<\/b><\/p>\n<p class=\"p1\">En caso de que entienda que sus derechos han sido desatendidos por nuestra entidad, puede formular una reclamaci\u00f3n en la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, a trav\u00e9s de alguno de los medios siguientes:<\/p>\n<p class=\"p1\"><b>Sede electr\u00f3nica<\/b>: <a href=\"http:\/\/www.agpd.es\"><span class=\"s1\">www.agpd.es<\/span><\/a><\/p>\n<p class=\"p1\"><b>Direcci\u00f3n postal<\/b>: Agencia Espa\u00f1ola de Protecci\u00f3n de Datos C\/ Jorge Juan, 6 28001-Madrid<\/p>\n<p class=\"p1\"><b>V\u00eda telef\u00f3nica<\/b>: Telf. 901 100 099 Telf. 91 266 35 17<\/p>\n<p class=\"p1\">Formular una reclamaci\u00f3n en la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos no conlleva ning\u00fan coste y no es necesaria la asistencia de abogado ni procurador.<\/p>\n<p class=\"p1\"><em>Luc\u00eda Iribarren Mac\u00edas<\/em> ha adecuado esta web a las exigencias del Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo de 27 de abril de 2016 relativo a la protecci\u00f3n de las personas f\u00edsicas (RGPD), la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales (LOPDGDD), as\u00ed como con la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSICE o LSSI).<\/p>\n<p class=\"p1\"><em><span class=\"s2\">\u00a9 Todos los derechos reservados: <\/span>Luc\u00eda Iribarren Mac\u00edas<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>AVISO LEGAL Gracias por visitar este sitio web. Lee detenidamente los T\u00e9rminos y Condiciones que constan en este documento, ya que el uso de este sitio web implica la expresa y plena aceptaci\u00f3n de los mismos, en la versi\u00f3n publicada en el momento en que accedes al mismo. Le recomendamos que lea atentamente este documento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-100","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Privacidad - Cl\u00ednica Dental Luc\u00eda Iribarren<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad - Cl\u00ednica Dental Luc\u00eda Iribarren\" \/>\n<meta property=\"og:description\" content=\"AVISO LEGAL Gracias por visitar este sitio web. Lee detenidamente los T\u00e9rminos y Condiciones que constan en este documento, ya que el uso de este sitio web implica la expresa y plena aceptaci\u00f3n de los mismos, en la versi\u00f3n publicada en el momento en que accedes al mismo. Le recomendamos que lea atentamente este documento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Dental Luc\u00eda Iribarren\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T19:30:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1094\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/index.php\\\/politica-de-privacidad\\\/\",\"url\":\"https:\\\/\\\/www.clinicairibarren.es\\\/index.php\\\/politica-de-privacidad\\\/\",\"name\":\"Pol\u00edtica de Privacidad - Cl\u00ednica Dental Luc\u00eda Iribarren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/index.php\\\/politica-de-privacidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/index.php\\\/politica-de-privacidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.clinicairibarren.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Captura-de-pantalla-2025-03-26-a-las-19.19.18-1024x425.png\",\"datePublished\":\"2025-03-10T10:42:07+00:00\",\"dateModified\":\"2025-04-01T19:30:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/index.php\\\/politica-de-privacidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clinicairibarren.es\\\/index.php\\\/politica-de-privacidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/index.php\\\/politica-de-privacidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.clinicairibarren.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Captura-de-pantalla-2025-03-26-a-las-19.19.18.png\",\"contentUrl\":\"https:\\\/\\\/www.clinicairibarren.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Captura-de-pantalla-2025-03-26-a-las-19.19.18.png\",\"width\":1094,\"height\":454},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/index.php\\\/politica-de-privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.clinicairibarren.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/#website\",\"url\":\"https:\\\/\\\/www.clinicairibarren.es\\\/\",\"name\":\"Cl\u00ednica Dental Luc\u00eda Iribarren\",\"description\":\"Clinica dental Luc\u00eda Iribarren, tu dentista en A Coru\u00f1a\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/#organization\"},\"alternateName\":\"tu dentista de confianza en Coru\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clinicairibarren.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/#organization\",\"name\":\"Cl\u00ednica Luc\u00eda Iribarren\",\"url\":\"https:\\\/\\\/www.clinicairibarren.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.clinicairibarren.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Clinica-Iribarren-logo-Color-02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.clinicairibarren.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Clinica-Iribarren-logo-Color-02.jpg\",\"width\":2243,\"height\":1415,\"caption\":\"Cl\u00ednica Luc\u00eda Iribarren\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clinicairibarren.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidad - Cl\u00ednica Dental Luc\u00eda Iribarren","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de Privacidad - Cl\u00ednica Dental Luc\u00eda Iribarren","og_description":"AVISO LEGAL Gracias por visitar este sitio web. Lee detenidamente los T\u00e9rminos y Condiciones que constan en este documento, ya que el uso de este sitio web implica la expresa y plena aceptaci\u00f3n de los mismos, en la versi\u00f3n publicada en el momento en que accedes al mismo. Le recomendamos que lea atentamente este documento [&hellip;]","og_url":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/","og_site_name":"Cl\u00ednica Dental Luc\u00eda Iribarren","article_modified_time":"2025-04-01T19:30:29+00:00","og_image":[{"width":1094,"height":454,"url":"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/","url":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/","name":"Pol\u00edtica de Privacidad - Cl\u00ednica Dental Luc\u00eda Iribarren","isPartOf":{"@id":"https:\/\/www.clinicairibarren.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/#primaryimage"},"image":{"@id":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18-1024x425.png","datePublished":"2025-03-10T10:42:07+00:00","dateModified":"2025-04-01T19:30:29+00:00","breadcrumb":{"@id":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/#primaryimage","url":"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18.png","contentUrl":"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Captura-de-pantalla-2025-03-26-a-las-19.19.18.png","width":1094,"height":454},{"@type":"BreadcrumbList","@id":"https:\/\/www.clinicairibarren.es\/index.php\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.clinicairibarren.es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidad"}]},{"@type":"WebSite","@id":"https:\/\/www.clinicairibarren.es\/#website","url":"https:\/\/www.clinicairibarren.es\/","name":"Cl\u00ednica Dental Luc\u00eda Iribarren","description":"Clinica dental Luc\u00eda Iribarren, tu dentista en A Coru\u00f1a","publisher":{"@id":"https:\/\/www.clinicairibarren.es\/#organization"},"alternateName":"tu dentista de confianza en Coru\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clinicairibarren.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.clinicairibarren.es\/#organization","name":"Cl\u00ednica Luc\u00eda Iribarren","url":"https:\/\/www.clinicairibarren.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicairibarren.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Clinica-Iribarren-logo-Color-02.jpg","contentUrl":"https:\/\/www.clinicairibarren.es\/wp-content\/uploads\/2025\/03\/Clinica-Iribarren-logo-Color-02.jpg","width":2243,"height":1415,"caption":"Cl\u00ednica Luc\u00eda Iribarren"},"image":{"@id":"https:\/\/www.clinicairibarren.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.clinicairibarren.es\/index.php\/wp-json\/wp\/v2\/pages\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clinicairibarren.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clinicairibarren.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clinicairibarren.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clinicairibarren.es\/index.php\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":13,"href":"https:\/\/www.clinicairibarren.es\/index.php\/wp-json\/wp\/v2\/pages\/100\/revisions"}],"predecessor-version":[{"id":625,"href":"https:\/\/www.clinicairibarren.es\/index.php\/wp-json\/wp\/v2\/pages\/100\/revisions\/625"}],"wp:attachment":[{"href":"https:\/\/www.clinicairibarren.es\/index.php\/wp-json\/wp\/v2\/media?parent=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}